{"id":58183,"date":"2024-12-08T15:07:16","date_gmt":"2024-12-08T15:07:16","guid":{"rendered":"http:\/\/saaremaazoo.ee\/product\/gourmet-gift-pack-2\/"},"modified":"2024-12-23T15:26:03","modified_gmt":"2024-12-23T15:26:03","slug":"gourmet-gift-pack-2","status":"publish","type":"product","link":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/","title":{"rendered":"Gourmet gift pack"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"58183\" class=\"elementor elementor-58183\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae7afef elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"ae7afef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1487fcd sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1487fcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-995a365 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"995a365\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-070def6 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"070def6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9b03fee elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"9b03fee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f83ecce sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f83ecce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fbca208 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fbca208\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c26f82f elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width sc_fly_static elementor-widget elementor-widget-icon-list\" data-id=\"c26f82f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gourmet package &#8211; 40\u20ac<br \/>\n-Rand&amp;Ross non-alcoholic gl\u00f6gg.<br \/>\n-Mo Saaremaa OLD SAARE cheese.<br \/>\n-Risto R\u00e4nk Farming pickled quail eggs.<br \/>\n-Epi farm cheese jam.<\/p>\n","protected":false},"featured_media":57777,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[311],"product_tag":[],"class_list":{"0":"post-58183","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gifts","8":"first","9":"outofstock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gourmet gift pack - Saaremaa Zoo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gourmet gift pack - Saaremaa Zoo\" \/>\n<meta property=\"og:description\" content=\"Gourmet package - 40\u20ac -Rand&amp;Ross non-alcoholic gl\u00f6gg. -Mo Saaremaa OLD SAARE cheese. -Risto R\u00e4nk Farming pickled quail eggs. -Epi farm cheese jam.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Saaremaa Zoo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/saaremaazoo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-23T15:26:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saaremaazoo.ee\/wp-content\/uploads\/2024\/12\/20221113_125206-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/\",\"url\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/\",\"name\":\"Gourmet gift pack - Saaremaa Zoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saaremaazoo.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/20221113_125206-scaled-1.jpg\",\"datePublished\":\"2024-12-08T15:07:16+00:00\",\"dateModified\":\"2024-12-23T15:26:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/saaremaazoo.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/20221113_125206-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/saaremaazoo.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/20221113_125206-scaled-1.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/product\\\/gourmet-gift-pack-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pood\",\"item\":\"https:\\\/\\\/saaremaazoo.ee\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gourmet gift pack\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/\",\"name\":\"Saaremaa Zoo\",\"description\":\"Saaremaa esimene Loomaaed\",\"publisher\":{\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/#organization\",\"name\":\"Saaremaa Loomaaed\",\"alternateName\":\"Saaremaa Zoo\",\"url\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/saaremaazoo.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-cropped-saaremaazoo_magnet_leemur__1__page-0001-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/saaremaazoo.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-cropped-saaremaazoo_magnet_leemur__1__page-0001-removebg-preview.png\",\"width\":467,\"height\":325,\"caption\":\"Saaremaa Loomaaed\"},\"image\":{\"@id\":\"https:\\\/\\\/saaremaazoo.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/saaremaazoo\",\"https:\\\/\\\/www.instagram.com\\\/saaremaazoo\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gourmet gift pack - Saaremaa Zoo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/","og_locale":"en_US","og_type":"article","og_title":"Gourmet gift pack - Saaremaa Zoo","og_description":"Gourmet package - 40\u20ac -Rand&amp;Ross non-alcoholic gl\u00f6gg. -Mo Saaremaa OLD SAARE cheese. -Risto R\u00e4nk Farming pickled quail eggs. -Epi farm cheese jam.","og_url":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/","og_site_name":"Saaremaa Zoo","article_publisher":"https:\/\/www.facebook.com\/saaremaazoo","article_modified_time":"2024-12-23T15:26:03+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/saaremaazoo.ee\/wp-content\/uploads\/2024\/12\/20221113_125206-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/","url":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/","name":"Gourmet gift pack - Saaremaa Zoo","isPartOf":{"@id":"https:\/\/saaremaazoo.ee\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/#primaryimage"},"image":{"@id":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/#primaryimage"},"thumbnailUrl":"https:\/\/saaremaazoo.ee\/wp-content\/uploads\/2024\/12\/20221113_125206-scaled-1.jpg","datePublished":"2024-12-08T15:07:16+00:00","dateModified":"2024-12-23T15:26:03+00:00","breadcrumb":{"@id":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/#primaryimage","url":"https:\/\/saaremaazoo.ee\/wp-content\/uploads\/2024\/12\/20221113_125206-scaled-1.jpg","contentUrl":"https:\/\/saaremaazoo.ee\/wp-content\/uploads\/2024\/12\/20221113_125206-scaled-1.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/saaremaazoo.ee\/en\/product\/gourmet-gift-pack-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/saaremaazoo.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Pood","item":"https:\/\/saaremaazoo.ee\/pood\/"},{"@type":"ListItem","position":3,"name":"Gourmet gift pack"}]},{"@type":"WebSite","@id":"https:\/\/saaremaazoo.ee\/en\/#website","url":"https:\/\/saaremaazoo.ee\/en\/","name":"Saaremaa Zoo","description":"Saaremaa esimene Loomaaed","publisher":{"@id":"https:\/\/saaremaazoo.ee\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saaremaazoo.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/saaremaazoo.ee\/en\/#organization","name":"Saaremaa Loomaaed","alternateName":"Saaremaa Zoo","url":"https:\/\/saaremaazoo.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/saaremaazoo.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/saaremaazoo.ee\/wp-content\/uploads\/2024\/12\/cropped-cropped-saaremaazoo_magnet_leemur__1__page-0001-removebg-preview.png","contentUrl":"https:\/\/saaremaazoo.ee\/wp-content\/uploads\/2024\/12\/cropped-cropped-saaremaazoo_magnet_leemur__1__page-0001-removebg-preview.png","width":467,"height":325,"caption":"Saaremaa Loomaaed"},"image":{"@id":"https:\/\/saaremaazoo.ee\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/saaremaazoo","https:\/\/www.instagram.com\/saaremaazoo\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/product\/58183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/comments?post=58183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/media\/57777"}],"wp:attachment":[{"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/media?parent=58183"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/product_brand?post=58183"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/product_cat?post=58183"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/saaremaazoo.ee\/en\/wp-json\/wp\/v2\/product_tag?post=58183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}